{"id":48079,"date":"1970-01-01T09:00:00","date_gmt":"1970-01-01T00:00:00","guid":{"rendered":"https:\/\/stg2.kawajun.biz\/en\/hardware\/products\/item2422\/"},"modified":"2025-09-29T15:54:06","modified_gmt":"2025-09-29T06:54:06","slug":"item2422","status":"publish","type":"products","link":"https:\/\/www.kawajun.biz\/en\/hardware\/products\/item2422\/","title":{"rendered":"SE113 Paper Holder (SE-113-XC)"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"products_category":[7],"class_list":["post-48079","products","type-products","status-publish","hentry","products_category-bathroomaccessories"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.kawajun.biz\/en\/hardware\/wp-json\/wp\/v2\/products\/48079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kawajun.biz\/en\/hardware\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/www.kawajun.biz\/en\/hardware\/wp-json\/wp\/v2\/types\/products"}],"wp:attachment":[{"href":"https:\/\/www.kawajun.biz\/en\/hardware\/wp-json\/wp\/v2\/media?parent=48079"}],"wp:term":[{"taxonomy":"products_category","embeddable":true,"href":"https:\/\/www.kawajun.biz\/en\/hardware\/wp-json\/wp\/v2\/products_category?post=48079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}